{"id":7888,"count":121,"description":"","link":"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/","name":"\u30ac\u30a4\u30c9","slug":"guides-jp","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v25.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u30ac\u30a4\u30c9 Archives - Eldorado Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u30ac\u30a4\u30c9 Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/\" \/>\n<meta property=\"og:site_name\" content=\"Eldorado Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EldoradoGg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/\",\"url\":\"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/\",\"name\":\"\u30ac\u30a4\u30c9 Archives - Eldorado Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.eldorado.gg\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eldorado.gg\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30ac\u30a4\u30c9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eldorado.gg\/blog\/#website\",\"url\":\"https:\/\/www.eldorado.gg\/blog\/\",\"name\":\"Eldorado.gg Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eldorado.gg\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eldorado.gg\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eldorado.gg\/blog\/#organization\",\"name\":\"Eldorado.gg Marketplace\",\"url\":\"https:\/\/www.eldorado.gg\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.eldorado.gg\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eldorado.gg\/blog\/wp-content\/uploads\/2025\/07\/eldorado-logo.png\",\"contentUrl\":\"https:\/\/www.eldorado.gg\/blog\/wp-content\/uploads\/2025\/07\/eldorado-logo.png\",\"width\":1500,\"height\":1500,\"caption\":\"Eldorado.gg Marketplace\"},\"image\":{\"@id\":\"https:\/\/www.eldorado.gg\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eldoradogg.official\/\",\"https:\/\/x.com\/EldoradoGg\",\"https:\/\/www.reddit.com\/r\/EldoradoGG\/\",\"https:\/\/www.tiktok.com\/@eldoradogg1\",\"https:\/\/www.youtube.com\/c\/EldoradoGG\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u30ac\u30a4\u30c9 Archives - Eldorado Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/","og_locale":"en_US","og_type":"article","og_title":"\u30ac\u30a4\u30c9 Archives","og_url":"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/","og_site_name":"Eldorado Blog","twitter_card":"summary_large_image","twitter_site":"@EldoradoGg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/","url":"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/","name":"\u30ac\u30a4\u30c9 Archives - Eldorado Blog","isPartOf":{"@id":"https:\/\/www.eldorado.gg\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldorado.gg\/blog\/jp\/category\/guides-jp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eldorado.gg\/blog\/"},{"@type":"ListItem","position":2,"name":"\u30ac\u30a4\u30c9"}]},{"@type":"WebSite","@id":"https:\/\/www.eldorado.gg\/blog\/#website","url":"https:\/\/www.eldorado.gg\/blog\/","name":"Eldorado.gg Blog","description":"","publisher":{"@id":"https:\/\/www.eldorado.gg\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldorado.gg\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eldorado.gg\/blog\/#organization","name":"Eldorado.gg Marketplace","url":"https:\/\/www.eldorado.gg\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eldorado.gg\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.eldorado.gg\/blog\/wp-content\/uploads\/2025\/07\/eldorado-logo.png","contentUrl":"https:\/\/www.eldorado.gg\/blog\/wp-content\/uploads\/2025\/07\/eldorado-logo.png","width":1500,"height":1500,"caption":"Eldorado.gg Marketplace"},"image":{"@id":"https:\/\/www.eldorado.gg\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eldoradogg.official\/","https:\/\/x.com\/EldoradoGg","https:\/\/www.reddit.com\/r\/EldoradoGG\/","https:\/\/www.tiktok.com\/@eldoradogg1","https:\/\/www.youtube.com\/c\/EldoradoGG"]}]}},"_links":{"self":[{"href":"https:\/\/www.eldorado.gg\/blog\/wp-json\/wp\/v2\/categories\/7888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldorado.gg\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.eldorado.gg\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.eldorado.gg\/blog\/wp-json\/wp\/v2\/posts?categories=7888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}